{"id":456,"date":"2018-04-24T10:30:14","date_gmt":"2018-04-24T08:30:14","guid":{"rendered":"http:\/\/gruene-ov-stuttgart.de\/sued\/?p=456"},"modified":"2018-04-28T10:46:52","modified_gmt":"2018-04-28T08:46:52","slug":"neues-verkehrskonzept-fuer-den-marienplatz","status":"publish","type":"post","link":"https:\/\/gruene-ov-stuttgart.de\/sued\/verkehr\/neues-verkehrskonzept-fuer-den-marienplatz\/","title":{"rendered":"Neues Verkehrskonzept f\u00fcr den n\u00f6rdlichen Bereich des Marienplatzes"},"content":{"rendered":"<p>Der Marienplatz kommt mit seinem bestehenden Verkehrskonzept an seine Grenze \u2013 und oft wird diese auch \u00fcberschritten. Konzepte zur Entflechtung der Verkehrsstr\u00f6me im Bereich des Marienplatzes wurden vom Bezirksbeirat bereits im Dezember 2013 (03.12.2013 Nr. 193) und April 2015 (21.04.2015 Nr. 102) beantragt.<\/p>\n<p>Die Situation:<br \/>\nDie Verkehrsf\u00fchrung der Hauptradroute Nr. 1 \u00fcber den Platzbereich ist un\u00fcbersichtlich. Die F\u00fchrung zusammen mit den Fu\u00dfg\u00e4ngern ist durch die hohe Frequentierung des Platzes nicht mehr angepasst. Dies f\u00fchrt zu einem chaotischen und oft regelwidrigen Verhalten aller Verkehrsteilnehmer*innen.<\/p>\n<p>&#8211; die Ein- und Ausfahrt T\u00fcbinger Stra\u00dfe (Fahrradstra\u00dfe) ist mit der Querung der T\u00fcbinger- bzw. Hohenstaufenstra\u00dfe sehr un\u00fcbersichtlich;<br \/>\n&#8211; die ausgeschilderte Route \u00fcber den Platz verl\u00e4uft gemeinsam mit den Fu\u00dfg\u00e4ngern, querende Fu\u00dfg\u00e4ngerstr\u00f6me von Haltestellen (Bus-, Stadt-, Zahnradbahn, Taxistand) und Fu\u00dfg\u00e4nger\u00fcberg\u00e4ngen f\u00fchren zu zus\u00e4tzlichen Gef\u00e4hrdungen;<br \/>\n&#8211; die Ein- und Ausfahrt M\u00f6hringer Stra\u00dfe ist eng, Fu\u00dfg\u00e4nger aus dem Supermarkt queren die Strecke;<\/p>\n<p>Bei der alternativen Benutzung der Fahrbahnen im Bereich des Marienplatzes (von der Fahrradstra\u00dfe kommend) ist derzeit unklar, wie die Hauptradroute \/ M\u00f6hringer Stra\u00dfe wieder erreicht wird. Bei der Einm\u00fcndung M\u00f6hringer Stra\u00dfe haben entweder Fu\u00dfg\u00e4nger oder Autofahrer rot. Da die Radfahrer*innen von der Stra\u00dfe auf den Fu\u00dfweg wechseln ist unklar welche Ampel gilt.<\/p>\n<p>Wir bitten im Rahmen der Planung zu pr\u00fcfen, ob die Hauptradroute 1 im gekennzeichneten Bereich mit separaten Fahrradspuren oder als Fahrradstra\u00dfe \u00fcber die B\u00f6blinger Stra\u00dfe gef\u00fchrt werden kann.<\/p>\n<p>Dies k\u00f6nnte zum Beispiel durch:<br \/>\n&#8211; eine kompaktere Anordnung von Fahr- und Parkbereichen (zur Zeit drei Fahrbahnen im Bereich Marienplatz, breite Fahrbahnen in der anschlie\u00dfenden B\u00f6blinger Stra\u00dfe);<br \/>\n&#8211; Verlegung oder Verkleinerung der \u201eVerkehrsinsel\u201c im Bereich des Marienplatzes mit Bushaltestelle, Taxipark- und Fu\u00dfg\u00e4ngerzone;<br \/>\n&#8211; eine ge\u00e4nderte Verkehrsf\u00fchrung f\u00fcr Autofahrer*innen (z.B. B\u00f6blinger Stra\u00dfe als Einbahnstra\u00dfe);<br \/>\nerreicht werden.<\/p>\n<p><strong>Deshalb haben wir im Bezirksbeirat Stuttgart-S\u00fcd beantragt:<\/strong><\/p>\n<p>Der Bezirksbeirat Stuttgart-S\u00fcd bittet die Verwaltung ein Konzept zur Neuordnung des Verkehrs \u2013 insbesondere F\u00fchrung der Hauptradroute Nr. 1 &#8211; im n\u00f6rdlichen Teil des Marienplatzes (siehe Planskizze) zu beauftragen.<br \/>\nZiel der Planung sollte eine Entflechtung der Verkehrsstr\u00f6me und die Erh\u00f6hung der Verkehrssicherheit sein. Dabei ist es besonders wichtig, Fu\u00dfg\u00e4ngerbereiche von Fahrradspuren frei zu halten. Eine ge\u00e4nderte F\u00fchrung der Hauptradroute 1 im Bereich des Marienplatzes sollte das ber\u00fccksichtigen.<\/p>\n<p>Der Antrag wurde am 24.4.2018 im Bezirksbeirat mit gro\u00dfer Mehrheit angenommen.<\/p>\n<p>In der Diskussion wurde auch der Vorschlag gemacht, in dem ganzen Bereich die Geschwindigkeit stark zu reduzieren, bis hin zu einer gemischten Verkehrsfl\u00e4che f\u00fcr alle mit Schritttempo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Marienplatz kommt mit seinem bestehenden Verkehrskonzept an seine Grenze \u2013 und oft wird diese auch \u00fcberschritten. Konzepte zur Entflechtung der Verkehrsstr\u00f6me im Bereich des Marienplatzes wurden vom Bezirksbeirat bereits&#8230; <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,14,29,9],"tags":[],"_links":{"self":[{"href":"https:\/\/gruene-ov-stuttgart.de\/sued\/wp-json\/wp\/v2\/posts\/456"}],"collection":[{"href":"https:\/\/gruene-ov-stuttgart.de\/sued\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gruene-ov-stuttgart.de\/sued\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gruene-ov-stuttgart.de\/sued\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gruene-ov-stuttgart.de\/sued\/wp-json\/wp\/v2\/comments?post=456"}],"version-history":[{"count":4,"href":"https:\/\/gruene-ov-stuttgart.de\/sued\/wp-json\/wp\/v2\/posts\/456\/revisions"}],"predecessor-version":[{"id":462,"href":"https:\/\/gruene-ov-stuttgart.de\/sued\/wp-json\/wp\/v2\/posts\/456\/revisions\/462"}],"wp:attachment":[{"href":"https:\/\/gruene-ov-stuttgart.de\/sued\/wp-json\/wp\/v2\/media?parent=456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gruene-ov-stuttgart.de\/sued\/wp-json\/wp\/v2\/categories?post=456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gruene-ov-stuttgart.de\/sued\/wp-json\/wp\/v2\/tags?post=456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}